{"id":3810,"date":"2022-03-15T08:24:07","date_gmt":"2022-03-15T07:24:07","guid":{"rendered":"http:\/\/bounsel.com\/bounsel-asiste-a-la-reapertura-de-google-for-startups-campus\/"},"modified":"2023-04-12T14:17:54","modified_gmt":"2023-04-12T13:17:54","slug":"bounsel-asiste-a-la-reapertura-de-google-for-startups-campus","status":"publish","type":"post","link":"https:\/\/www.bounsel.com\/es\/blog\/bounsel-asiste-a-la-reapertura-de-google-for-startups-campus\/","title":{"rendered":"Bounsel en la reapertura de Google for Startups Campus"},"content":{"rendered":"<p><p id=\"\">Despu&eacute;s de 2 a&ntilde;os con todo el trabajo y el desarrollo de los programas en remoto, Google for Startups reabre Campus Madrid.<\/p>\n<p>El pasado jueves 10 de marzo, nuestra CEO, Pilar Prados, asisti&oacute; al evento de reapertura, donde pudo descubrir el precioso espacio de trabajo que han creado en Campus Madrid y disfrutar de este acto junto a Francisco Polo (Alto Comisionado para Espa&ntilde;a Naci&oacute;n Emprendedora), Reyes Maroto (Ministra de Industria, Comercio y Turismo), Sof&iacute;a Benjumea (Directora de Google for Startups EMEA) y el resto de la comunidad.<\/p>\n<p>&#128153; &iexcl;Gracias por contar con Bounsel!<\/p>\n<p id=\"\">Puedes leer las noticias completas a continuaci&oacute;n:<\/p>\n<figure class=\"w-richtext-figure-type-image w-richtext-align-fullwidth\" style=\"max-width:1200px\" data-rt-type=\"image\" data-rt-align=\"fullwidth\" data-rt-max-width=\"1200px\">\n<div><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"http:\/\/bounsel.com\/wp-content\/uploads\/2023\/03\/635112397768dde1c64421f3_reapertura-campus-madrid-google-2640899-min.jpeg\" loading=\"lazy\"><\/div>\n<\/figure>\n<p id=\"\">&zwj;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de 2 a\u00f1os con todo el trabajo y el desarrollo de los programas en remoto, Google for Startups reabre Campus Madrid.<\/p>\n","protected":false},"author":11,"featured_media":3811,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[97],"tags":[],"class_list":["post-3810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bounsel-es"],"_links":{"self":[{"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/posts\/3810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/comments?post=3810"}],"version-history":[{"count":0,"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/posts\/3810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/media\/3811"}],"wp:attachment":[{"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/media?parent=3810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/categories?post=3810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/tags?post=3810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}