{"id":4458,"date":"2022-03-24T09:00:19","date_gmt":"2022-03-24T08:00:19","guid":{"rendered":"http:\/\/bounsel.com\/xavi-creatividad-en-el-departamento-de-marketing-en-bounsel\/"},"modified":"2023-04-05T10:24:04","modified_gmt":"2023-04-05T09:24:04","slug":"xavi-creatividad-en-el-departamento-de-marketing-en-bounsel","status":"publish","type":"post","link":"https:\/\/www.bounsel.com\/es\/blog\/xavi-creatividad-en-el-departamento-de-marketing-en-bounsel\/","title":{"rendered":"Xavi se une a Bounsel en el \u00e1rea de Marketing"},"content":{"rendered":"<p id=\"\">Mi nombre es Javier Ortega, aunque los que me conocen me llaman Xavi. Tengo 22 a\u00f1os y he nacido y crecido aqu\u00ed, en la terreta, Valencia. Pese a ello, estudi\u00e9 en el Colegio Alem\u00e1n de Valencia, por lo que considero que tengo ese peque\u00f1o gen alem\u00e1n.<\/p>\n<p id=\"\">Actualmente estudio el Grado de Comunicaci\u00f3n Audiovisual en la Universitat de Val\u00e8ncia y me he incorporado recientemente al Departamento de Marketing de Bounsel. Adem\u00e1s, estoy trabajando tambi\u00e9n como Community Manager en el club de f\u00fatbol del Colegio Alem\u00e1n de Valencia.<\/p>\n<p id=\"\">Siempre me ha interesado todo lo relacionado con la creatividad: m\u00fasica, fotograf\u00eda, audiovisual, etc. Es por eso que me considero una persona creativa, curiosa. No obstante, soy tambi\u00e9n una persona organizada y tranquila, aunque esa libertad creativa pueda llevar a pensar lo contrario. No me gusta estar quieto, as\u00ed que siempre estoy participando en distintos proyectos creativos, tanto musicales como audiovisuales.<\/p>\n<p id=\"\">Mi principal afici\u00f3n es la m\u00fasica, de hecho toco el saxof\u00f3n en la Uni\u00f3n Musical de Castellar Oliveral, la guitarra y produzco m\u00fasica en mi tiempo libre. De todas maneras, soy un apasionado de lo audiovisual, as\u00ed que si no estoy mezclando una canci\u00f3n, probablemente est\u00e9 editando un v\u00eddeo. Me interesan mucho los idiomas, el deporte y disfruto mucho estando con mis amigos.<\/p>\n<p id=\"\">Estoy enamorado de mi ciudad natal: llevo las fallas en la sangre, me paso el verano en la playa y me encanta la gastronom\u00eda mediterr\u00e1nea, aunque no descarto en un futuro irme durante un tiempo por estudios o trabajo. Eso s\u00ed, siempre con idea de volver a mi tierra.<\/p>\n<p id=\"\">Xavi.<\/p>\n<p id=\"\"><strong id=\"\">\u00bfT\u00fa tambi\u00e9n quieres formar parte del equipo? Descubre m\u00e1s sobre <\/strong><a href=\"https:\/\/es.bounsel.com\/\" target=\"_blank\" rel=\"noopener nofollow\"><strong id=\"\">nosotros<\/strong><\/a><strong id=\"\"> y \u00a1<\/strong><a href=\"https:\/\/es.bounsel.com\/careers\" target=\"_blank\" rel=\"noopener nofollow\"><strong id=\"\">\u00fanete<\/strong><\/a><strong id=\"\"> a Bounsel!<\/strong><\/p>\n<p id=\"\">\u200d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mi nombre es Javier Ortega, aunque los que me conocen me llaman Xavi. Tengo 22 a\u00f1os y he nacido y crecido aqu\u00ed, en la terreta, Valencia.<\/p>\n","protected":false},"author":11,"featured_media":4459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[97],"tags":[105],"class_list":["post-4458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bounsel-es","tag-bounsel-es"],"_links":{"self":[{"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/posts\/4458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/comments?post=4458"}],"version-history":[{"count":0,"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/posts\/4458\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/media\/4459"}],"wp:attachment":[{"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/media?parent=4458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/categories?post=4458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bounsel.com\/es\/wp-json\/wp\/v2\/tags?post=4458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}